{"id":36293,"date":"2025-11-06T00:00:00","date_gmt":"2024-07-20T00:00:00","guid":{"rendered":null},"modified":"2025-11-06T00:00:00","modified_gmt":"2025-11-06T00:00:00","slug":"01030269","status":"publish","type":"product","link":"https:\/\/e-laskaridis.gr\/en\/product\/01030269\/","title":{"rendered":"\u039b\u0391\u03a3\u03a4\u0399\u03a7\u039f \u03a6\u039f\u03a5\u03a3\u039a\u0391 \u03a3\u03a4\u039f \u03a0\u039b\u0391\u0399 MC0602 \u039b\u0391\u03a3\u03a4\u0399\u03a7\u039f (\u03c4\u03c3\u03b9\u03bc\u03bf\u03c5\u03c7\u03b1) \u0393\u0399\u0391 \u03a0\u039f\u03a1\u03a4\u0391 \u039c\u0395\u0393\u0391"},"content":{"rendered":"<p>\u039b\u03ac\u03c3\u03c4\u03b9\u03c7\u03bf,\u0391\u03bc\u03b1\u03be\u03ce\u03bc\u03b1\u03c4\u03bf\u03c2,(\u03a4\u03b9\u03bc\u03ae,\u03b1\u03bd\u03ac,\u03bc\u03ad\u03c4\u03c1\u03bf)&#x0D;<br \/>\n\u0394\u03b9\u03b1\u03c3\u03c4\u03ac\u03c3\u03b5\u03b9\u03c2,\u03c3\u03b5,\u03c7\u03b9\u03bb\u03b9\u03bf\u03c3\u03c4\u03ac,(mm)<\/p>","protected":false},"excerpt":{"rendered":"<p>\u039b\u03ac\u03c3\u03c4\u03b9\u03c7\u03bf,\u0391\u03bc\u03b1\u03be\u03ce\u03bc\u03b1\u03c4\u03bf\u03c2,(\u03a4\u03b9\u03bc\u03ae,\u03b1\u03bd\u03ac,\u03bc\u03ad\u03c4\u03c1\u03bf)&#x0D; \u0394\u03b9\u03b1\u03c3\u03c4\u03ac\u03c3\u03b5\u03b9\u03c2,\u03c3\u03b5,\u03c7\u03b9\u03bb\u03b9\u03bf\u03c3\u03c4\u03ac,(mm)<\/p>","protected":false},"featured_media":36295,"template":"","meta":[],"product-make":[],"product-model":[],"product-trim":[],"pwb-brand":[17690],"product_brand":[],"pa_category":[17380,17374],"product_tag":[20404],"pa_brand":[],"pa_liters":[],"pa_size":[],"pa_\u03b9\u03be\u03ce\u03b4\u03b5\u03c2":[],"class_list":["post-36293","product","type-product","status-publish","has-post-thumbnail","pwb-brand-mc-parts","product_cat-antallaktika","product_cat-antallaktika-plaisio","product_tag-01116826100146-5330231115405-010300036","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"product_attributes":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u039b\u0391\u03a3\u03a4\u0399\u03a7\u039f \u03a6\u039f\u03a5\u03a3\u039a\u0391 \u03a3\u03a4\u039f \u03a0\u039b\u0391\u0399 MC0602 \u039b\u0391\u03a3\u03a4\u0399\u03a7\u039f (\u03c4\u03c3\u03b9\u03bc\u03bf\u03c5\u03c7\u03b1) \u0393\u0399\u0391 \u03a0\u039f\u03a1\u03a4\u0391 \u039c\u0395\u0393\u0391 - \u039b\u0391\u03a3\u039a\u0391\u03a1\u0399\u0394\u0397\u03a3 \u0391\u03a0. \u0395\u039c\u039c\u0391\u039d\u039f\u03a5\u0397\u039b<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/e-laskaridis.gr\/en\/product\/01030269\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u039b\u0391\u03a3\u03a4\u0399\u03a7\u039f \u03a6\u039f\u03a5\u03a3\u039a\u0391 \u03a3\u03a4\u039f \u03a0\u039b\u0391\u0399 MC0602 \u039b\u0391\u03a3\u03a4\u0399\u03a7\u039f (\u03c4\u03c3\u03b9\u03bc\u03bf\u03c5\u03c7\u03b1) \u0393\u0399\u0391 \u03a0\u039f\u03a1\u03a4\u0391 \u039c\u0395\u0393\u0391 - \u039b\u0391\u03a3\u039a\u0391\u03a1\u0399\u0394\u0397\u03a3 \u0391\u03a0. \u0395\u039c\u039c\u0391\u039d\u039f\u03a5\u0397\u039b\" \/>\n<meta property=\"og:description\" content=\"\u039b\u03ac\u03c3\u03c4\u03b9\u03c7\u03bf,\u0391\u03bc\u03b1\u03be\u03ce\u03bc\u03b1\u03c4\u03bf\u03c2,(\u03a4\u03b9\u03bc\u03ae,\u03b1\u03bd\u03ac,\u03bc\u03ad\u03c4\u03c1\u03bf)&#xD; \u0394\u03b9\u03b1\u03c3\u03c4\u03ac\u03c3\u03b5\u03b9\u03c2,\u03c3\u03b5,\u03c7\u03b9\u03bb\u03b9\u03bf\u03c3\u03c4\u03ac,(mm)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/e-laskaridis.gr\/en\/product\/01030269\/\" \/>\n<meta property=\"og:site_name\" content=\"\u039b\u0391\u03a3\u039a\u0391\u03a1\u0399\u0394\u0397\u03a3 \u0391\u03a0. \u0395\u039c\u039c\u0391\u039d\u039f\u03a5\u0397\u039b\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/e-laskaridis.gr\/wp-content\/uploads\/products\/3629569-1\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/e-laskaridis.gr\\\/product\\\/01030269\\\/\",\"url\":\"https:\\\/\\\/e-laskaridis.gr\\\/product\\\/01030269\\\/\",\"name\":\"\u039b\u0391\u03a3\u03a4\u0399\u03a7\u039f \u03a6\u039f\u03a5\u03a3\u039a\u0391 \u03a3\u03a4\u039f \u03a0\u039b\u0391\u0399 MC0602 \u039b\u0391\u03a3\u03a4\u0399\u03a7\u039f (\u03c4\u03c3\u03b9\u03bc\u03bf\u03c5\u03c7\u03b1) \u0393\u0399\u0391 \u03a0\u039f\u03a1\u03a4\u0391 \u039c\u0395\u0393\u0391 - \u039b\u0391\u03a3\u039a\u0391\u03a1\u0399\u0394\u0397\u03a3 \u0391\u03a0. \u0395\u039c\u039c\u0391\u039d\u039f\u03a5\u0397\u039b\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/e-laskaridis.gr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/e-laskaridis.gr\\\/product\\\/01030269\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/e-laskaridis.gr\\\/product\\\/01030269\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/e-laskaridis.gr\\\/wp-content\\\/uploads\\\/products\\\/3629569-1\",\"datePublished\":\"2024-07-20T00:00:00+00:00\",\"dateModified\":\"2025-11-06T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/e-laskaridis.gr\\\/product\\\/01030269\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/e-laskaridis.gr\\\/product\\\/01030269\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/e-laskaridis.gr\\\/product\\\/01030269\\\/#primaryimage\",\"url\":\"https:\\\/\\\/e-laskaridis.gr\\\/wp-content\\\/uploads\\\/products\\\/3629569-1\",\"contentUrl\":\"https:\\\/\\\/e-laskaridis.gr\\\/wp-content\\\/uploads\\\/products\\\/3629569-1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/e-laskaridis.gr\\\/product\\\/01030269\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae\",\"item\":\"https:\\\/\\\/e-laskaridis.gr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u039a\u03b1\u03c4\u03ac\u03c3\u03c4\u03b7\u03bc\u03b1\",\"item\":\"https:\\\/\\\/e-laskaridis.gr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u039b\u0391\u03a3\u03a4\u0399\u03a7\u039f \u03a6\u039f\u03a5\u03a3\u039a\u0391 \u03a3\u03a4\u039f \u03a0\u039b\u0391\u0399 MC0602 \u039b\u0391\u03a3\u03a4\u0399\u03a7\u039f (\u03c4\u03c3\u03b9\u03bc\u03bf\u03c5\u03c7\u03b1) \u0393\u0399\u0391 \u03a0\u039f\u03a1\u03a4\u0391 \u039c\u0395\u0393\u0391\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/e-laskaridis.gr\\\/#website\",\"url\":\"https:\\\/\\\/e-laskaridis.gr\\\/\",\"name\":\"\u039b\u0391\u03a3\u039a\u0391\u03a1\u0399\u0394\u0397\u03a3 \u0391\u03a0. \u0395\u039c\u039c\u0391\u039d\u039f\u03a5\u0397\u039b\",\"description\":\"\u0391\u03bd\u03c4\u03b1\u03bb\u03bb\u03b1\u03ba\u03c4\u03b9\u03ba\u03ac \u03bf\u03c7\u03b7\u03bc\u03ac\u03c4\u03c9\u03bd \u03ba\u03b1\u03b9 \u03c3\u03c4\u03c1\u03b1\u03c4\u03b9\u03c9\u03c4\u03b9\u03ba\u03ce\u03bd \u03bf\u03c7\u03b7\u03bc\u03ac\u03c4\u03c9\u03bd\",\"publisher\":{\"@id\":\"https:\\\/\\\/e-laskaridis.gr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/e-laskaridis.gr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/e-laskaridis.gr\\\/#organization\",\"name\":\"\u039b\u0391\u03a3\u039a\u0391\u03a1\u0399\u0394\u0397\u03a3 \u0391\u03a0. \u0395\u039c\u039c\u0391\u039d\u039f\u03a5\u0397\u039b\",\"url\":\"https:\\\/\\\/e-laskaridis.gr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/e-laskaridis.gr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/e-laskaridis.gr\\\/wp-content\\\/uploads\\\/logo_small.png?fit=460%2C141&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/e-laskaridis.gr\\\/wp-content\\\/uploads\\\/logo_small.png?fit=460%2C141&ssl=1\",\"width\":460,\"height\":141,\"caption\":\"\u039b\u0391\u03a3\u039a\u0391\u03a1\u0399\u0394\u0397\u03a3 \u0391\u03a0. \u0395\u039c\u039c\u0391\u039d\u039f\u03a5\u0397\u039b\"},\"image\":{\"@id\":\"https:\\\/\\\/e-laskaridis.gr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u039b\u0391\u03a3\u03a4\u0399\u03a7\u039f \u03a6\u039f\u03a5\u03a3\u039a\u0391 \u03a3\u03a4\u039f \u03a0\u039b\u0391\u0399 MC0602 \u039b\u0391\u03a3\u03a4\u0399\u03a7\u039f (\u03c4\u03c3\u03b9\u03bc\u03bf\u03c5\u03c7\u03b1) \u0393\u0399\u0391 \u03a0\u039f\u03a1\u03a4\u0391 \u039c\u0395\u0393\u0391 - \u039b\u0391\u03a3\u039a\u0391\u03a1\u0399\u0394\u0397\u03a3 \u0391\u03a0. \u0395\u039c\u039c\u0391\u039d\u039f\u03a5\u0397\u039b","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/e-laskaridis.gr\/en\/product\/01030269\/","og_locale":"en_US","og_type":"article","og_title":"\u039b\u0391\u03a3\u03a4\u0399\u03a7\u039f \u03a6\u039f\u03a5\u03a3\u039a\u0391 \u03a3\u03a4\u039f \u03a0\u039b\u0391\u0399 MC0602 \u039b\u0391\u03a3\u03a4\u0399\u03a7\u039f (\u03c4\u03c3\u03b9\u03bc\u03bf\u03c5\u03c7\u03b1) \u0393\u0399\u0391 \u03a0\u039f\u03a1\u03a4\u0391 \u039c\u0395\u0393\u0391 - \u039b\u0391\u03a3\u039a\u0391\u03a1\u0399\u0394\u0397\u03a3 \u0391\u03a0. \u0395\u039c\u039c\u0391\u039d\u039f\u03a5\u0397\u039b","og_description":"\u039b\u03ac\u03c3\u03c4\u03b9\u03c7\u03bf,\u0391\u03bc\u03b1\u03be\u03ce\u03bc\u03b1\u03c4\u03bf\u03c2,(\u03a4\u03b9\u03bc\u03ae,\u03b1\u03bd\u03ac,\u03bc\u03ad\u03c4\u03c1\u03bf)&#x0D; \u0394\u03b9\u03b1\u03c3\u03c4\u03ac\u03c3\u03b5\u03b9\u03c2,\u03c3\u03b5,\u03c7\u03b9\u03bb\u03b9\u03bf\u03c3\u03c4\u03ac,(mm)","og_url":"https:\/\/e-laskaridis.gr\/en\/product\/01030269\/","og_site_name":"\u039b\u0391\u03a3\u039a\u0391\u03a1\u0399\u0394\u0397\u03a3 \u0391\u03a0. \u0395\u039c\u039c\u0391\u039d\u039f\u03a5\u0397\u039b","article_modified_time":"2025-11-06T00:00:00+00:00","og_image":[{"url":"https:\/\/e-laskaridis.gr\/wp-content\/uploads\/products\/3629569-1","width":1,"height":1,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/e-laskaridis.gr\/product\/01030269\/","url":"https:\/\/e-laskaridis.gr\/product\/01030269\/","name":"\u039b\u0391\u03a3\u03a4\u0399\u03a7\u039f \u03a6\u039f\u03a5\u03a3\u039a\u0391 \u03a3\u03a4\u039f \u03a0\u039b\u0391\u0399 MC0602 \u039b\u0391\u03a3\u03a4\u0399\u03a7\u039f (\u03c4\u03c3\u03b9\u03bc\u03bf\u03c5\u03c7\u03b1) \u0393\u0399\u0391 \u03a0\u039f\u03a1\u03a4\u0391 \u039c\u0395\u0393\u0391 - \u039b\u0391\u03a3\u039a\u0391\u03a1\u0399\u0394\u0397\u03a3 \u0391\u03a0. \u0395\u039c\u039c\u0391\u039d\u039f\u03a5\u0397\u039b","isPartOf":{"@id":"https:\/\/e-laskaridis.gr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/e-laskaridis.gr\/product\/01030269\/#primaryimage"},"image":{"@id":"https:\/\/e-laskaridis.gr\/product\/01030269\/#primaryimage"},"thumbnailUrl":"https:\/\/e-laskaridis.gr\/wp-content\/uploads\/products\/3629569-1","datePublished":"2024-07-20T00:00:00+00:00","dateModified":"2025-11-06T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/e-laskaridis.gr\/product\/01030269\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/e-laskaridis.gr\/product\/01030269\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/e-laskaridis.gr\/product\/01030269\/#primaryimage","url":"https:\/\/e-laskaridis.gr\/wp-content\/uploads\/products\/3629569-1","contentUrl":"https:\/\/e-laskaridis.gr\/wp-content\/uploads\/products\/3629569-1"},{"@type":"BreadcrumbList","@id":"https:\/\/e-laskaridis.gr\/product\/01030269\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae","item":"https:\/\/e-laskaridis.gr\/"},{"@type":"ListItem","position":2,"name":"\u039a\u03b1\u03c4\u03ac\u03c3\u03c4\u03b7\u03bc\u03b1","item":"https:\/\/e-laskaridis.gr\/shop\/"},{"@type":"ListItem","position":3,"name":"\u039b\u0391\u03a3\u03a4\u0399\u03a7\u039f \u03a6\u039f\u03a5\u03a3\u039a\u0391 \u03a3\u03a4\u039f \u03a0\u039b\u0391\u0399 MC0602 \u039b\u0391\u03a3\u03a4\u0399\u03a7\u039f (\u03c4\u03c3\u03b9\u03bc\u03bf\u03c5\u03c7\u03b1) \u0393\u0399\u0391 \u03a0\u039f\u03a1\u03a4\u0391 \u039c\u0395\u0393\u0391"}]},{"@type":"WebSite","@id":"https:\/\/e-laskaridis.gr\/#website","url":"https:\/\/e-laskaridis.gr\/","name":"LASKARIDIS AP. EMMANUEL","description":"Spare parts for vehicles and military vehicles","publisher":{"@id":"https:\/\/e-laskaridis.gr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/e-laskaridis.gr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/e-laskaridis.gr\/#organization","name":"LASKARIDIS AP. EMMANUEL","url":"https:\/\/e-laskaridis.gr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/e-laskaridis.gr\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/e-laskaridis.gr\/wp-content\/uploads\/logo_small.png?fit=460%2C141&ssl=1","contentUrl":"https:\/\/i0.wp.com\/e-laskaridis.gr\/wp-content\/uploads\/logo_small.png?fit=460%2C141&ssl=1","width":460,"height":141,"caption":"\u039b\u0391\u03a3\u039a\u0391\u03a1\u0399\u0394\u0397\u03a3 \u0391\u03a0. \u0395\u039c\u039c\u0391\u039d\u039f\u03a5\u0397\u039b"},"image":{"@id":"https:\/\/e-laskaridis.gr\/#\/schema\/logo\/image\/"}}]}},"brands":[{"id":17690,"name":"MC parts","slug":"mc-parts"}],"_links":{"self":[{"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/product\/36293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/media\/36295"}],"wp:attachment":[{"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/media?parent=36293"}],"wp:term":[{"taxonomy":"product-make","embeddable":true,"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/product-make?post=36293"},{"taxonomy":"product-model","embeddable":true,"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/product-model?post=36293"},{"taxonomy":"product-trim","embeddable":true,"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/product-trim?post=36293"},{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/pwb-brand?post=36293"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/product_brand?post=36293"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/pa_category?post=36293"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/product_tag?post=36293"},{"taxonomy":"pa_brand","embeddable":true,"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/pa_brand?post=36293"},{"taxonomy":"pa_liters","embeddable":true,"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/pa_liters?post=36293"},{"taxonomy":"pa_size","embeddable":true,"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/pa_size?post=36293"},{"taxonomy":"pa_\u03b9\u03be\u03ce\u03b4\u03b5\u03c2","embeddable":true,"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/pa_\u03b9\u03be\u03ce\u03b4\u03b5\u03c2?post=36293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}