{"id":42233,"date":"2025-02-11T00:00:00","date_gmt":"2024-07-23T00:00:00","guid":{"rendered":null},"modified":"2025-02-11T00:00:00","modified_gmt":"2025-02-11T00:00:00","slug":"01010010972","status":"publish","type":"product","link":"https:\/\/e-laskaridis.gr\/en\/product\/01010010972\/","title":{"rendered":"\u0398\u0395\u03a1\u039c\u039f\u03a3\u03a4\u0391\u03a4\u0397\u03a3 \u039c\u0395 \u03a6\u039f\u03a5\u03a3\u039a\u0391(\u039c\u039f\u039d\u039f \u03a3\u0392\u039f\u03a5\u03a1\u0391) M\/S CDI (W204-W211)TX47492D (6462000015)"},"content":{"rendered":"<p>thermostatis,me,fouska,ms,mercedes,CDi,W204,W211,TI3192,6462000015,6462030075,820571,TH36392G1,244592,V30990102,6462030275,TH36392G1,684792,41017492D,244592,6462030075,820571,245192355,862020492,TH684792J,9000722,QTH596K,CT5106,5350392,50192,862019392,FTS48392,0219240<\/p>","protected":false},"excerpt":{"rendered":"<p>thermostatis,me,fouska,ms,mercedes,CDi,W204,W211,TI3192,6462000015,6462030075,820571,TH36392G1,244592,V30990102,6462030275,TH36392G1,684792,41017492D,244592,6462030075,820571,245192355,862020492,TH684792J,9000722,QTH596K,CT5106,5350392,50192,862019392,FTS48392,0219240<\/p>","protected":false},"featured_media":12931,"template":"","meta":[],"product-make":[],"product-model":[17388],"product-trim":[],"pwb-brand":[17462],"product_brand":[],"pa_category":[17380,17369,17367],"product_tag":[34970,34971,28272,34964,34966,34967,34968,34969,34963,34965,31355,45839,34972],"pa_brand":[17381],"pa_liters":[],"pa_size":[],"pa_\u03b9\u03be\u03ce\u03b4\u03b5\u03c2":[],"class_list":["post-42233","product","type-product","status-publish","has-post-thumbnail","product-model-mercedes","pwb-brand-mahle-knecht","product_cat-antallaktika","product_cat-antallaktika-hlektrologika-diafora","product_cat-antallaktika-mhxanika","product_tag-34970","product_tag-34971","product_tag-28272","product_tag-34964","product_tag-34966","product_tag-34967","product_tag-34968","product_tag-34969","product_tag-34963","product_tag-34965","product_tag-dt1132h","product_tag-ti3192","product_tag-tx47492d","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"product_attributes":{"pa_brand":{"17381":"MERCEDES"}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0398\u0395\u03a1\u039c\u039f\u03a3\u03a4\u0391\u03a4\u0397\u03a3 \u039c\u0395 \u03a6\u039f\u03a5\u03a3\u039a\u0391(\u039c\u039f\u039d\u039f \u03a3\u0392\u039f\u03a5\u03a1\u0391) M\/S CDI (W204-W211)TX47492D (6462000015) - \u039b\u0391\u03a3\u039a\u0391\u03a1\u0399\u0394\u0397\u03a3 \u0391\u03a0. \u0395\u039c\u039c\u0391\u039d\u039f\u03a5\u0397\u039b<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/e-laskaridis.gr\/en\/product\/01010010972\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0398\u0395\u03a1\u039c\u039f\u03a3\u03a4\u0391\u03a4\u0397\u03a3 \u039c\u0395 \u03a6\u039f\u03a5\u03a3\u039a\u0391(\u039c\u039f\u039d\u039f \u03a3\u0392\u039f\u03a5\u03a1\u0391) M\/S CDI (W204-W211)TX47492D (6462000015) - \u039b\u0391\u03a3\u039a\u0391\u03a1\u0399\u0394\u0397\u03a3 \u0391\u03a0. \u0395\u039c\u039c\u0391\u039d\u039f\u03a5\u0397\u039b\" \/>\n<meta property=\"og:description\" content=\"thermostatis,me,fouska,ms,mercedes,CDi,W204,W211,TI3192,6462000015,6462030075,820571,TH36392G1,244592,V30990102,6462030275,TH36392G1,684792,41017492D,244592,6462030075,820571,245192355,862020492,TH684792J,9000722,QTH596K,CT5106,5350392,50192,862019392,FTS48392,0219240\" \/>\n<meta property=\"og:url\" content=\"https:\/\/e-laskaridis.gr\/en\/product\/01010010972\/\" \/>\n<meta property=\"og:site_name\" content=\"\u039b\u0391\u03a3\u039a\u0391\u03a1\u0399\u0394\u0397\u03a3 \u0391\u03a0. \u0395\u039c\u039c\u0391\u039d\u039f\u03a5\u0397\u039b\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-11T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/e-laskaridis.gr\/wp-content\/uploads\/products\/12931\u03ba\u03cc\u03bd\u03b1\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/e-laskaridis.gr\\\/product\\\/01010010972\\\/\",\"url\":\"https:\\\/\\\/e-laskaridis.gr\\\/product\\\/01010010972\\\/\",\"name\":\"\u0398\u0395\u03a1\u039c\u039f\u03a3\u03a4\u0391\u03a4\u0397\u03a3 \u039c\u0395 \u03a6\u039f\u03a5\u03a3\u039a\u0391(\u039c\u039f\u039d\u039f \u03a3\u0392\u039f\u03a5\u03a1\u0391) M\\\/S CDI (W204-W211)TX47492D (6462000015) - \u039b\u0391\u03a3\u039a\u0391\u03a1\u0399\u0394\u0397\u03a3 \u0391\u03a0. \u0395\u039c\u039c\u0391\u039d\u039f\u03a5\u0397\u039b\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/e-laskaridis.gr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/e-laskaridis.gr\\\/product\\\/01010010972\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/e-laskaridis.gr\\\/product\\\/01010010972\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/e-laskaridis.gr\\\/wp-content\\\/uploads\\\/products\\\/12931\u03ba\u03cc\u03bd\u03b1\",\"datePublished\":\"2024-07-23T00:00:00+00:00\",\"dateModified\":\"2025-02-11T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/e-laskaridis.gr\\\/product\\\/01010010972\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/e-laskaridis.gr\\\/product\\\/01010010972\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/e-laskaridis.gr\\\/product\\\/01010010972\\\/#primaryimage\",\"url\":\"https:\\\/\\\/e-laskaridis.gr\\\/wp-content\\\/uploads\\\/products\\\/12931\u03ba\u03cc\u03bd\u03b1\",\"contentUrl\":\"https:\\\/\\\/e-laskaridis.gr\\\/wp-content\\\/uploads\\\/products\\\/12931\u03ba\u03cc\u03bd\u03b1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/e-laskaridis.gr\\\/product\\\/01010010972\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae\",\"item\":\"https:\\\/\\\/e-laskaridis.gr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u039a\u03b1\u03c4\u03ac\u03c3\u03c4\u03b7\u03bc\u03b1\",\"item\":\"https:\\\/\\\/e-laskaridis.gr\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0398\u0395\u03a1\u039c\u039f\u03a3\u03a4\u0391\u03a4\u0397\u03a3 \u039c\u0395 \u03a6\u039f\u03a5\u03a3\u039a\u0391(\u039c\u039f\u039d\u039f \u03a3\u0392\u039f\u03a5\u03a1\u0391) M\\\/S CDI (W204-W211)TX47492D (6462000015)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/e-laskaridis.gr\\\/#website\",\"url\":\"https:\\\/\\\/e-laskaridis.gr\\\/\",\"name\":\"\u039b\u0391\u03a3\u039a\u0391\u03a1\u0399\u0394\u0397\u03a3 \u0391\u03a0. \u0395\u039c\u039c\u0391\u039d\u039f\u03a5\u0397\u039b\",\"description\":\"\u0391\u03bd\u03c4\u03b1\u03bb\u03bb\u03b1\u03ba\u03c4\u03b9\u03ba\u03ac \u03bf\u03c7\u03b7\u03bc\u03ac\u03c4\u03c9\u03bd \u03ba\u03b1\u03b9 \u03c3\u03c4\u03c1\u03b1\u03c4\u03b9\u03c9\u03c4\u03b9\u03ba\u03ce\u03bd \u03bf\u03c7\u03b7\u03bc\u03ac\u03c4\u03c9\u03bd\",\"publisher\":{\"@id\":\"https:\\\/\\\/e-laskaridis.gr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/e-laskaridis.gr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/e-laskaridis.gr\\\/#organization\",\"name\":\"\u039b\u0391\u03a3\u039a\u0391\u03a1\u0399\u0394\u0397\u03a3 \u0391\u03a0. \u0395\u039c\u039c\u0391\u039d\u039f\u03a5\u0397\u039b\",\"url\":\"https:\\\/\\\/e-laskaridis.gr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/e-laskaridis.gr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/e-laskaridis.gr\\\/wp-content\\\/uploads\\\/logo_small.png?fit=460%2C141&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/e-laskaridis.gr\\\/wp-content\\\/uploads\\\/logo_small.png?fit=460%2C141&ssl=1\",\"width\":460,\"height\":141,\"caption\":\"\u039b\u0391\u03a3\u039a\u0391\u03a1\u0399\u0394\u0397\u03a3 \u0391\u03a0. \u0395\u039c\u039c\u0391\u039d\u039f\u03a5\u0397\u039b\"},\"image\":{\"@id\":\"https:\\\/\\\/e-laskaridis.gr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0398\u0395\u03a1\u039c\u039f\u03a3\u03a4\u0391\u03a4\u0397\u03a3 \u039c\u0395 \u03a6\u039f\u03a5\u03a3\u039a\u0391(\u039c\u039f\u039d\u039f \u03a3\u0392\u039f\u03a5\u03a1\u0391) M\/S CDI (W204-W211)TX47492D (6462000015) - \u039b\u0391\u03a3\u039a\u0391\u03a1\u0399\u0394\u0397\u03a3 \u0391\u03a0. \u0395\u039c\u039c\u0391\u039d\u039f\u03a5\u0397\u039b","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/e-laskaridis.gr\/en\/product\/01010010972\/","og_locale":"en_US","og_type":"article","og_title":"\u0398\u0395\u03a1\u039c\u039f\u03a3\u03a4\u0391\u03a4\u0397\u03a3 \u039c\u0395 \u03a6\u039f\u03a5\u03a3\u039a\u0391(\u039c\u039f\u039d\u039f \u03a3\u0392\u039f\u03a5\u03a1\u0391) M\/S CDI (W204-W211)TX47492D (6462000015) - \u039b\u0391\u03a3\u039a\u0391\u03a1\u0399\u0394\u0397\u03a3 \u0391\u03a0. \u0395\u039c\u039c\u0391\u039d\u039f\u03a5\u0397\u039b","og_description":"thermostatis,me,fouska,ms,mercedes,CDi,W204,W211,TI3192,6462000015,6462030075,820571,TH36392G1,244592,V30990102,6462030275,TH36392G1,684792,41017492D,244592,6462030075,820571,245192355,862020492,TH684792J,9000722,QTH596K,CT5106,5350392,50192,862019392,FTS48392,0219240","og_url":"https:\/\/e-laskaridis.gr\/en\/product\/01010010972\/","og_site_name":"\u039b\u0391\u03a3\u039a\u0391\u03a1\u0399\u0394\u0397\u03a3 \u0391\u03a0. \u0395\u039c\u039c\u0391\u039d\u039f\u03a5\u0397\u039b","article_modified_time":"2025-02-11T00:00:00+00:00","og_image":[{"url":"https:\/\/e-laskaridis.gr\/wp-content\/uploads\/products\/12931\u03ba\u03cc\u03bd\u03b1","width":1,"height":1,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/e-laskaridis.gr\/product\/01010010972\/","url":"https:\/\/e-laskaridis.gr\/product\/01010010972\/","name":"\u0398\u0395\u03a1\u039c\u039f\u03a3\u03a4\u0391\u03a4\u0397\u03a3 \u039c\u0395 \u03a6\u039f\u03a5\u03a3\u039a\u0391(\u039c\u039f\u039d\u039f \u03a3\u0392\u039f\u03a5\u03a1\u0391) M\/S CDI (W204-W211)TX47492D (6462000015) - \u039b\u0391\u03a3\u039a\u0391\u03a1\u0399\u0394\u0397\u03a3 \u0391\u03a0. \u0395\u039c\u039c\u0391\u039d\u039f\u03a5\u0397\u039b","isPartOf":{"@id":"https:\/\/e-laskaridis.gr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/e-laskaridis.gr\/product\/01010010972\/#primaryimage"},"image":{"@id":"https:\/\/e-laskaridis.gr\/product\/01010010972\/#primaryimage"},"thumbnailUrl":"https:\/\/e-laskaridis.gr\/wp-content\/uploads\/products\/12931\u03ba\u03cc\u03bd\u03b1","datePublished":"2024-07-23T00:00:00+00:00","dateModified":"2025-02-11T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/e-laskaridis.gr\/product\/01010010972\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/e-laskaridis.gr\/product\/01010010972\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/e-laskaridis.gr\/product\/01010010972\/#primaryimage","url":"https:\/\/e-laskaridis.gr\/wp-content\/uploads\/products\/12931\u03ba\u03cc\u03bd\u03b1","contentUrl":"https:\/\/e-laskaridis.gr\/wp-content\/uploads\/products\/12931\u03ba\u03cc\u03bd\u03b1"},{"@type":"BreadcrumbList","@id":"https:\/\/e-laskaridis.gr\/product\/01010010972\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae","item":"https:\/\/e-laskaridis.gr\/"},{"@type":"ListItem","position":2,"name":"\u039a\u03b1\u03c4\u03ac\u03c3\u03c4\u03b7\u03bc\u03b1","item":"https:\/\/e-laskaridis.gr\/shop\/"},{"@type":"ListItem","position":3,"name":"\u0398\u0395\u03a1\u039c\u039f\u03a3\u03a4\u0391\u03a4\u0397\u03a3 \u039c\u0395 \u03a6\u039f\u03a5\u03a3\u039a\u0391(\u039c\u039f\u039d\u039f \u03a3\u0392\u039f\u03a5\u03a1\u0391) M\/S CDI (W204-W211)TX47492D (6462000015)"}]},{"@type":"WebSite","@id":"https:\/\/e-laskaridis.gr\/#website","url":"https:\/\/e-laskaridis.gr\/","name":"LASKARIDIS AP. EMMANUEL","description":"Spare parts for vehicles and military vehicles","publisher":{"@id":"https:\/\/e-laskaridis.gr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/e-laskaridis.gr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/e-laskaridis.gr\/#organization","name":"LASKARIDIS AP. EMMANUEL","url":"https:\/\/e-laskaridis.gr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/e-laskaridis.gr\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/e-laskaridis.gr\/wp-content\/uploads\/logo_small.png?fit=460%2C141&ssl=1","contentUrl":"https:\/\/i0.wp.com\/e-laskaridis.gr\/wp-content\/uploads\/logo_small.png?fit=460%2C141&ssl=1","width":460,"height":141,"caption":"\u039b\u0391\u03a3\u039a\u0391\u03a1\u0399\u0394\u0397\u03a3 \u0391\u03a0. \u0395\u039c\u039c\u0391\u039d\u039f\u03a5\u0397\u039b"},"image":{"@id":"https:\/\/e-laskaridis.gr\/#\/schema\/logo\/image\/"}}]}},"brands":[{"id":17462,"name":"MAHLE KNECHT","slug":"mahle-knecht"}],"_links":{"self":[{"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/product\/42233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/media\/12931"}],"wp:attachment":[{"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/media?parent=42233"}],"wp:term":[{"taxonomy":"product-make","embeddable":true,"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/product-make?post=42233"},{"taxonomy":"product-model","embeddable":true,"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/product-model?post=42233"},{"taxonomy":"product-trim","embeddable":true,"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/product-trim?post=42233"},{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/pwb-brand?post=42233"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/product_brand?post=42233"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/pa_category?post=42233"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/product_tag?post=42233"},{"taxonomy":"pa_brand","embeddable":true,"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/pa_brand?post=42233"},{"taxonomy":"pa_liters","embeddable":true,"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/pa_liters?post=42233"},{"taxonomy":"pa_size","embeddable":true,"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/pa_size?post=42233"},{"taxonomy":"pa_\u03b9\u03be\u03ce\u03b4\u03b5\u03c2","embeddable":true,"href":"https:\/\/e-laskaridis.gr\/en\/wp-json\/wp\/v2\/pa_\u03b9\u03be\u03ce\u03b4\u03b5\u03c2?post=42233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}